{"id":10112,"date":"2019-02-14T17:40:06","date_gmt":"2019-02-14T15:40:06","guid":{"rendered":"https:\/\/www.hiberus.com\/crecemos-contigo\/?p=10112"},"modified":"2025-08-06T11:33:47","modified_gmt":"2025-08-06T09:33:47","slug":"datos-protegidos-backup-servicio","status":"publish","type":"post","link":"https:\/\/www.hiberus.com\/crecemos-contigo\/datos-protegidos-backup-servicio\/","title":{"rendered":"Tus datos protegidos en la nube: recomendaciones de Backup como Servicio"},"content":{"rendered":"<p>Hoy en d\u00eda la informaci\u00f3n que contienen los sistemas inform\u00e1ticos con los que trabajan entidades del sector p\u00fablico y privado son uno de los activos m\u00e1s importantes para el desempe\u00f1o que cualquier actividad econ\u00f3mica.<\/p>\n<p><strong>Sufrir una p\u00e9rdida de datos<\/strong> sea cual fuere la raz\u00f3n (ataque cibern\u00e9tico, fallo de disco duro, virus encriptador, borrado accidental, incendios, robos, etc&#8230;) puede constituir un serio riesgo para la continuidad del negocio.\u00a0En un art\u00edculo anterior os habl\u00e1bamos de por qu\u00e9 es importante hacer una copia de seguridad con un servicio de backup remoto, pero hoy vamos a tratar algunas <strong>recomendaciones a tener en cuenta al seleccionar un proveedor de backup<\/strong> adecuado para realizar copias de seguridad en la nube y proteger tus archivos o los de tus clientes contra p\u00e9rdidas y eliminaciones.<\/p>\n<p>La copia de seguridad mediante un servicio de backup remoto, permite contar con una r\u00e9plica deslocalizada del centro de trabajo habitual de todos los archivos cr\u00edticos .aunque conviene hacer una serie de <strong>recomendaciones a la hora de contratar un servicio de backup remoto<\/strong>:<\/p>\n<h3>Tu reputaci\u00f3n est\u00e1 en juego<\/h3>\n<p>Revisa cuidadosamente las caracter\u00edsticas y beneficios del servicio de copias de seguridad que est\u00e1s\u00a0valorando.<\/p>\n<h3>Cobertura del servicio<\/h3>\n<p>No todas las empresas de backup en la nube ofrecen el mismo servicio, por lo que es importante profundizar en ello. Muchos proveedores dicen que ofrecen un historial a versiones anteriores, pero \u00bfdurante cu\u00e1nto tiempo? Es importante saber cu\u00e1ntas versiones de nuestros archivos guardan y durante cu\u00e1nto tiempo, ya que si hay un problema es posible que no podamos recuperar los archivos desde la fecha que los necesitamos.<\/p>\n<p>Compara y analiza las diferencias entre los diferentes proveedores para que puedas estar seguro de tu elecci\u00f3n.<\/p>\n<h3>Servicio y soporte<\/h3>\n<p>Cualquiera que sea la compa\u00f1\u00eda de backup que elijas, debes asegurarte de c\u00f3mo es su servicio de atenci\u00f3n al cliente. Si necesitas comunicarte con ellos por cualquier raz\u00f3n, ya sea por dudas de configuraci\u00f3n o por una situaci\u00f3n de emergencia, debes poder confiar en que tu proveedor de backup online estar\u00e1 all\u00ed para ayudarte a que los datos permanezcan seguros y protegidos.<\/p>\n<p>Aseg\u00farate de que el proveedor que elijas te ofrezca soporte t\u00e9cnico las 24 horas del d\u00eda, en caso de una emergencia o que, al menos, disponga de recursos y gu\u00edas de usuario para poder ayudarte a resolver r\u00e1pidamente los problemas por tu cuenta.<\/p>\n<p>&nbsp;<\/p>\n<h3>Copias cifradas<\/h3>\n<p><strong>La copia debe estar cifrada en origen<\/strong> para garantizar la total confidencialidad de los datos. Para ello la contrase\u00f1a de cifrado debe ser robusta alternando caract\u00e9res alfanum\u00e9ricos. Lo ideal ser\u00eda que los datos fueran cifrados mediante un c\u00f3digo de encriptaci\u00f3n de 2048 bits.<\/p>\n<h3>Seguridad de infraestructura<\/h3>\n<p><strong>Deber\u00edamos cotejar que las infraestructuras donde se van alojar nuestros datos<\/strong> tengan unas m\u00e9didas de seguridad m\u00ednimas tanto f\u00edsicas como t\u00e9cnicas. Igualmente es aconsejable es que los CPD est\u00e9n ubicados en Espa\u00f1a para garantizar que al menos cumplen las directivas impuestas en el Reglamento General de Protecci\u00f3n de Datos que entr\u00f3 en vigor el pasado 25 de mayo del 2018. En este aspecto es de valorar que el proveedor cuente con normas de calidad implantadas a este respecto<\/p>\n<h3>Responsabilidad en caso de p\u00e9rdida de datos<\/h3>\n<p>Deber\u00edamos <strong>consultar al proveedor qu\u00e9 tipo de responsabilidad asume<\/strong> en el caso de que por negligencia de \u00e9ste, los datos no puedan ser restaurados correctamente.<\/p>\n<h3>Desginaci\u00f3n de responsable<\/h3>\n<p>Deber\u00edamos delimitar <strong>qui\u00e9n debe asumir la supervisi\u00f3n de que las copias se realicen correctamente<\/strong> a diario con el objeto de que, llegado el momento de restaurar datos, \u00e9stos no est\u00e9n obsoletos, corruptos o directamente inservibles.<\/p>\n<h3>Backups online autom\u00e1ticos<\/h3>\n<p>Lo ideal es que no tengas que recordar hacer las copias de seguridad o verificar manualmente que la copia de seguridad se ha realizado correctamente. Hay demasiadas posibilidades de que haya un humano. Elige un proveedor de copias de seguridad que se ejecute de forma autom\u00e1tica y continua en segundo plano, realizando copias de seguridad de los archivos a medida que se crean y modifican sin interrumpir tus tareas del d\u00eda a d\u00eda.\u00a0El proveedor deber\u00eda <strong>monitorizar que los respaldos se realicen correctamente a diario<\/strong>, y en caso contrario darle soluci\u00f3n en el menor tiempo posible.<\/p>\n<p>&nbsp;<\/p>\n<p>Obviamente no todos los servicios de backup en la nube son iguales por lo que es de vital importancia tomar en consideraci\u00f3n multitud de factores. La continuidad de nuestra empresa puede depender de una decisi\u00f3n equivocada. En hiberus te ofrecemos el\u00a0<strong>mejor servicio\u00a0<\/strong>de backup remoto\u00a0para tu empresa. Tenemos 3 paquetes diferentes (profesional, gran ocupaci\u00f3n y premium) que se adaptar\u00e1n a tus necesidades y presupuesto.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda la informaci\u00f3n que contienen los sistemas inform\u00e1ticos con los que trabajan entidades del sector p\u00fablico y privado son uno&#8230;<\/p>\n","protected":false},"author":57,"featured_media":10113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_ayudawp_aiss_exclude":false,"_ayudawp_aiss_exclude_summary":false,"_ayudawp_aiss_summary":"","_ayudawp_aiss_summary_provider":"","_ayudawp_aiss_summary_hash":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-10112","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sistemas-cloud-computing"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/posts\/10112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/comments?post=10112"}],"version-history":[{"count":2,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/posts\/10112\/revisions"}],"predecessor-version":[{"id":58611,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/posts\/10112\/revisions\/58611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/media\/10113"}],"wp:attachment":[{"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/media?parent=10112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/categories?post=10112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hiberus.com\/crecemos-contigo\/wp-json\/wp\/v2\/tags?post=10112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}